{"id":1960,"date":"2022-07-08T09:28:56","date_gmt":"2022-07-08T07:28:56","guid":{"rendered":"https:\/\/www.scillasb.com\/?page_id=1960"},"modified":"2025-10-31T12:04:04","modified_gmt":"2025-10-31T11:04:04","slug":"privacy-gdpr-e-trattamento-dei-dati-personali","status":"publish","type":"page","link":"https:\/\/scillasb.com\/en\/privacy-gdpr-e-trattamento-dei-dati-personali\/","title":{"rendered":"Privacy: GDPR e trattamento dei dati personali"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1960\" class=\"elementor elementor-1960\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fb2a1c e-con-full e-flex e-con e-parent\" data-id=\"5fb2a1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-436155d elementor-widget elementor-widget-template\" data-id=\"436155d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3820\" class=\"elementor elementor-3820\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-45a3290 e-flex e-con-boxed e-con e-parent\" data-id=\"45a3290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a5f51f e-flex e-con-boxed e-con e-child\" data-id=\"2a5f51f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52e0ac7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"52e0ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Privacy: GDPR e trattamento dei dati personali<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c43a32b e-flex e-con-boxed e-con e-parent\" data-id=\"c43a32b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-23278bd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"23278bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-233a4d8 elementor-widget elementor-widget-heading\" data-id=\"233a4d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Modello Organizzativo Privacy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7933d0f elementor-widget elementor-widget-heading\" data-id=\"7933d0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La gestione completa degli adempimenti obbligatori<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9018039 elementor-widget elementor-widget-text-editor\" data-id=\"9018039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dal 25 Maggio 2018<\/strong>, tutte le aziende all\u2019interno della UE devono implementare le misure per la protezione di tutti i <strong>dati personali<\/strong> (dati identificativi, giudiziari, particolari, biometrici).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31a1649 e-flex e-con-boxed e-con e-parent\" data-id=\"31a1649\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9be5484 elementor-widget elementor-widget-text-editor\" data-id=\"9be5484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Lo standard ISO 27001 integra l\u2019articolo 32 del GDPR per il trattamento dei dati personali ed ogni Impresa \u00e8 chiamata a dotarsi di un <strong>Modello Organizzativo Privacy<\/strong>, ovvero un insieme di documenti e procedure per adempiere agli obblighi del <strong>Regolamento Europeo n. 2016\/679<\/strong> comunemente definito <strong>GDPR (General Data Protection Regulation)<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a76043f e-flex e-con-boxed e-con e-parent\" data-id=\"a76043f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-df7f1b8 e-con-full e-flex e-con e-child\" data-id=\"df7f1b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-060fa67 elementor-widget elementor-widget-heading\" data-id=\"060fa67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GDPR e trattamento dei dati personali: caratteristiche del servizio di consulenza\u00a0<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-291dbb7 elementor-widget elementor-widget-text-editor\" data-id=\"291dbb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>SCILLA SRL SB<\/strong> supporta l\u2019impresa in tutti gli adempimenti in materia privacy per non incorrere nelle pesanti sanzioni imposte dal GDPR e rispettando tutti i diritti degli interessati.<br \/>Di seguito un elenco sintetico e non esaustivo delle attivit\u00e0 erogate da <strong>SCILLA S.r.l. SB<\/strong> per adempiere alle prescrizioni definite dal <strong>GDPR.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73370ad e-con-full e-flex e-con e-child\" data-id=\"73370ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5ede5 elementor-widget elementor-widget-template\" data-id=\"9c5ede5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4455\" class=\"elementor elementor-4455\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-986f908 e-con-full e-flex e-con e-child\" data-id=\"986f908\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f07c87 elementor-widget elementor-widget-image\" data-id=\"0f07c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"155\" src=\"https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-300x155.png\" class=\"attachment-medium size-medium wp-image-1006\" alt=\"\" srcset=\"https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-300x155.png 300w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-500x258.png 500w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-700x364.png 700w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-200x103.png 200w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-400x206.png 400w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG-600x309.png 600w, https:\/\/scillasb.com\/wp-content\/uploads\/2021\/09\/SCILLA-SRL-SB-LOGO-SITO-INTESTAZIONE-PNG.png 706w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2d7d4c elementor-widget elementor-widget-heading\" data-id=\"f2d7d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Scelti da Aziende di ogni Settore<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a9e436 e-con-full e-flex e-con e-child\" data-id=\"4a9e436\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7178819 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7178819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Costruzioni e Infrastrutture<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Logistica e Trasporti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Farmaceutiche e Biomedicali<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-571060d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"571060d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Manifatturiero e Industria<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Laboratori di Ricerca<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servizi Professionali<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd47113 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bd47113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/scillasb.com\/en\/appuntamento\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo gratuito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0af4f13 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"0af4f13\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54b205c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"54b205c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GDPR e trattamento dei dati personali: approfondimenti sui servizi di consulenza<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95da6db e-flex e-con-boxed e-con e-parent\" data-id=\"95da6db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9dcc7aa e-con-full e-flex e-con e-child\" data-id=\"9dcc7aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c168a19 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"c168a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a57e37c7cd59\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-c168a19\">\n                        <a href=\"#collapse-47a21266a57e37c7cd59\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-47a21266a57e37c7cd59\" aria-expanded=\"true\" aria-controls=\"Collapse-47a21266a57e37c7cd59\">\n                            \n                            <span class=\"ekit-accordion-title\"> Analisi e valutazione dei rischi vincolati al trattamento dei dati<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_plus\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_minus-06\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-47a21266a57e37c7cd59\" class=\"show collapse\" aria-labelledby=\"primaryHeading-0-c168a19\" data-parent=\"#accordion-6a57e37c7cd59\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>\u00a0<strong>SCILLA S.r.l. SB<\/strong> tiene conto della <strong>natura<\/strong>, dell\u2019<strong>ambito di applicazione<\/strong>, del contesto e delle finalit\u00e0 del trattamento, nonch\u00e9 dei rischi aventi probabilit\u00e0 e gravit\u00e0 diverse per i <strong>diritti<\/strong> e le <strong>libert\u00e0<\/strong> delle persone fisiche individuando le misure tecniche e organizzative adeguate da mettere in atto per garantire, ed essere in grado di dimostrare, che il trattamento \u00e8 effettuato conformemente al presente<strong> regolamento<\/strong>.<\/p><p>\u00c9 la fase operativa in cui vengono acquisite informazioni ed evidenze di conformit\u00e0, ove disponibili, a partire dalla quale \u00e8 possibile pianificare le specifiche attivit\u00e0 di consulenza<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-c168a19\">\n                        <a href=\"#collapse-f5853556a57e37c7cd59\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f5853556a57e37c7cd59\" aria-expanded=\"false\" aria-controls=\"Collapse-f5853556a57e37c7cd59\">\n                            \n                            <span class=\"ekit-accordion-title\"> Individuazione dei ruoli ed elaborazione delle nomine di Responsabili e persone autorizzate<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_plus\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_minus-06\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f5853556a57e37c7cd59\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-c168a19\" data-parent=\"#accordion-6a57e37c7cd59\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>In alcuni casi da valutare \u00e8 obbligatoria la designazione di un <strong>Responsabile della Protezione dei Dati<\/strong> definito anche <strong>DPO<\/strong> <strong>(Data Protection Officer)<\/strong> che ha il compito di assolvere le funzioni di <strong>supporto, controllo e informative<\/strong> relativamente all'applicazione del <strong>Regolamento<\/strong> medesimo.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0230deb e-con-full e-flex e-con e-child\" data-id=\"0230deb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7fb7cc elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"a7fb7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a57e37c7d50f\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-a7fb7cc\">\n                        <a href=\"#collapse-47a21266a57e37c7d50f\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-47a21266a57e37c7d50f\" aria-expanded=\"false\" aria-controls=\"Collapse-47a21266a57e37c7d50f\">\n                            \n                            <span class=\"ekit-accordion-title\"> Produzione e adeguato aggiornamento di tutta la documentazione da adottare per realizzare misure di tutela<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_plus\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_minus-06\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-47a21266a57e37c7d50f\" class=\"collapse\" aria-labelledby=\"primaryHeading-0-a7fb7cc\" data-parent=\"#accordion-6a57e37c7d50f\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><strong>SCILLA S.r.l. SB<\/strong> supporta il Cliente nella predisposizione di tutta la documentazione per la presentazione dell\u2019istanza di autorizzazione all\u2019<strong>Ispettorato Provinciale del Lavoro<\/strong> obbligatoria per tutte le aziende che hanno installato un impianto di <strong>videosorveglianza<\/strong> all\u2019interno dei luoghi di lavoro.<\/p><p>Il Datore di Lavoro, in ogni azienda soggetta al D.Lgs. 81\/08 e s.m.i., deve nominare il\u00a0<strong>RSPP<\/strong>\u00a0e una delle possibili soluzioni, \u00e8 quella di individuarlo esternamente (RSPP esterno).<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-a7fb7cc\">\n                        <a href=\"#collapse-f5853556a57e37c7d50f\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f5853556a57e37c7d50f\" aria-expanded=\"false\" aria-controls=\"Collapse-f5853556a57e37c7d50f\">\n                            \n                            <span class=\"ekit-accordion-title\"> Pianificazione della formazione da erogare a tutti gli addetti che trattano dati personali<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_plus\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon_minus-06\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f5853556a57e37c7d50f\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-a7fb7cc\" data-parent=\"#accordion-6a57e37c7d50f\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Il <strong>GDPR<\/strong> ha introdotto l\u2019obbligo di formare tutti i lavoratori che hanno accesso a <strong>dati personali, amministrativi,<\/strong> di Clienti o del personale.<br \/>I destinatari del corso sono tutti i dipendenti che, all\u2019interno dell\u2019azienda, sono autorizzati ad eseguire il trattamento dei dati personali contenuti in documenti cartacei ed elettronici.<br \/><strong>SCILLA S.r.l. SB<\/strong> eroga corsi di formazione sia online, sia in aula, con <strong>progetti formativi<\/strong> specifici per il settore di appartenenza.<br \/>Il percorso didattico comprende un test di <strong>verifica finale<\/strong>, al termine del quale, verr\u00e0 rilasciato un attestato di formazione valido a norma di legge.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ff746e e-con-full e-flex e-con e-parent\" data-id=\"3ff746e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9645e68 elementor-widget elementor-widget-template\" data-id=\"9645e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4490\" class=\"elementor elementor-4490\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-0afb1c6 e-flex e-con-boxed e-con e-parent\" data-id=\"0afb1c6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c28f4a4 e-grid e-con-full e-con e-child\" data-id=\"c28f4a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01e6099 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"01e6099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vi stiamo aspettando per supportare i Vostri progetti<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed22345 elementor-widget elementor-widget-text-editor\" data-id=\"ed22345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Mettiti in contatto con noi oggi e rendiamo la tua attivit\u00e0 pi\u00f9 etica e sostenibile, centrando ogni obiettivo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fb4852 e-grid e-con-full e-con e-child\" data-id=\"7fb4852\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9ffbb elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4b9ffbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Contatto Telefonico\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-phone-handset\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" >\n\t\t\t\t\t\t\tContatto Telefonico\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPuoi contattarci telefonicamente e ricevere immediatamente le informazioni di cui hai bisogno. Troverai personale disponibile e preparato a rispondere alle tue esigenze\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2479f22 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2479f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Appuntamento Gratuito\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-megaphone1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" >\n\t\t\t\t\t\t\tAppuntamento Gratuito\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPuoi prenotare un appuntamento gratuito che potremo svolgere presso la tua sede o in videoconferenza. Basta contattarci e pianificare, nelle date disponibili, il nostro primo incontro\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f880cf2 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f880cf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Obiettivi Raggiunti\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-Target\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/scillasb.com\/en\/appuntamento\/\" >\n\t\t\t\t\t\t\tObiettivi Raggiunti\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIn questa sezione potresti trovare la soluzione che stai cercando. Abbiamo supportato i nostri Clienti a raggiungere gli obiettivi prefissati, garantendo impatti positivi, concreti, misurabili di sostenibilit\u00e0\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eef23e6 e-grid e-con-full e-con e-child\" data-id=\"eef23e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e02ab3e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e02ab3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/scillasb.com\/en\/appuntamento\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un appuntamento gratuito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Modello Organizzativo Privacy La gestione completa degli adempimenti obbligatori Dal 25 Maggio 2018, tutte le aziende all\u2019interno della UE devono implementare le misure per la protezione di tutti i dati personali (dati identificativi, giudiziari, particolari, biometrici). Lo standard ISO 27001 integra l\u2019articolo 32 del GDPR per il trattamento dei dati personali ed ogni Impresa \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3688,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1960","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"meta_box":[],"_links":{"self":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/pages\/1960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/comments?post=1960"}],"version-history":[{"count":32,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/pages\/1960\/revisions"}],"predecessor-version":[{"id":5077,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/pages\/1960\/revisions\/5077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media\/3688"}],"wp:attachment":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media?parent=1960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}