{"id":5374,"date":"2025-04-28T12:56:44","date_gmt":"2025-04-28T10:56:44","guid":{"rendered":"https:\/\/dev.scillasb.com\/?post_type=product&#038;p=5374"},"modified":"2025-05-27T12:21:53","modified_gmt":"2025-05-27T10:21:53","slug":"corso-di-formazione-addetti-alla-conduzione-di-piattaforme-di-lavoro-elevabili-ple","status":"publish","type":"product","link":"https:\/\/scillasb.com\/en\/product\/corso-di-formazione-addetti-alla-conduzione-di-piattaforme-di-lavoro-elevabili-ple\/","title":{"rendered":"Corso di formazione addetti alla conduzione di piattaforme di lavoro elevabili (PLE)"},"content":{"rendered":"<h4>PROGRAMMA DIDATTICO<\/h4>\n<p>AI SENSI DEGLI ARTT. 37 E 73, COMMA 5 DEL D. LGS. N. 81\/2008 CORR. D.LGS. N.106\/2009 E ACC. STATO-REGIONI DEL 22\/02\/2012 ALL. III<\/p>\n<p><strong>Modulo giuridico normativo (1 ore)<\/strong><\/p>\n<ul>\n<li>Presentazione del corso.<\/li>\n<li>Cenni di normativa generale in materia di igiene e sicurezza del lavoro con particolare riferimento ai lavori in quota ed all\u2019uso di attrezzature di lavoro per lavori in quota (D.Lgs. n. 81\/2008).<\/li>\n<li>Responsabilit\u00e0 dell\u2019operatore.<\/li>\n<\/ul>\n<p><strong>Modulo tecnico (3 ore)<\/strong><\/p>\n<ul>\n<li>Categorie di PLE: i vari tipi di PLE e descrizione delle caratteristiche generali e specifiche<\/li>\n<li>Componenti strutturali: sistemi di stabilizzazione, livellamento, telaio, torretta girevole, struttura a pantografo\/braccio elevabile.<br \/>\nDispositivi di comando e di sicurezza: individuazione dei dispositivi di comando e loro funzionamento, individuazione dei dispositivi di sicurezza e loro funzione.<\/li>\n<li>Controlli da effettuare prima dell\u2019utilizzo: controlli visivi e funzionali.<\/li>\n<li>DPI specifici da utilizzare con le PLE: caschi, imbracature, cordino di trattenuta e relative modalit\u00e0 di utilizzo inclusi i punti di aggancio in piattaforma.<\/li>\n<li>Modalit\u00e0 di utilizzo in sicurezza e rischi: analisi e valutazione dei rischi ricorrenti nell\u2019utilizzo delle PLE (rischi di elettrocuzione, rischi ambientali, di caduta dall\u2019alto, ecc.); spostamento e traslazione, posizionamento e stabilizzazione, azionamenti e manovre, rifornimento e parcheggio in modo sicuro a fine lavoro.<\/li>\n<li>Procedure operative di salvataggio: modalit\u00e0 di discesa in emergenza.<\/li>\n<\/ul>\n<p><strong><br \/>\nModulo pratico ai fini dell\u2019abilitazione all\u2019uso sia di PLE con stabilizzatori che di PLE senza stabilizzatori (6 ore).<\/strong><\/p>\n<ul>\n<li>Individuazione dei componenti strutturali: sistemi di stabilizzazione, livellamento, telaio, torretta girevole, struttura a pantografo\/braccio elevabile, piattaforma e relativi sistemi di collegamento.<\/li>\n<li>Dispositivi di comando e di sicurezza: identificazione dei dispositivi di comando e loro funzionamento, identificazione dei dispositivi di sicurezza e loro funzione.<\/li>\n<li>Controlli pre-utilizzo: controlli visivi e funzionali della PLE, dei dispositivi di comando, di segnalazione e di sicurezza previsti dal costruttore e dal manuale di istruzioni della PLE.<\/li>\n<li>Controlli prima del trasferimento su strada: verifica delle condizioni di assetto (presa di forza, struttura di sollevamento e stabilizzatori, ecc.).<\/li>\n<li>Pianificazione del percorso: pendenze, accesso, ostacoli sul percorso e in quota, condizioni del terreno.<\/li>\n<li>Movimentazione e posizionamento della PLE: delimitazione dell\u2019area di lavoro, segnaletica da predisporre su strade pubbliche, spostamento della PLE sul luogo di lavoro, posizionamento stabilizzatori a livellamento.<\/li>\n<li>Esercitazioni di pratiche operative: effettuazione di esercitazioni a due terzi dell\u2019area di lavoro, osservando le procedure operative di sicurezza. Simulazioni di movimentazioni della piattaforma in quota.<\/li>\n<li>Manovre di emergenza: effettuazione delle manovre di emergenza per il recupero a terra della piattaforma posizionata in quota.<\/li>\n<li>Messa a riposo della PLE a fine lavoro: parcheggio in area idonea, precauzioni contro l\u2019utilizzo non autorizzato. Modalit\u00e0 di ricarica delle batterie in sicurezza (per PLE munite di alimentazione a batterie).<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Il corso di formazione per addetti alla conduzione di piattaforme di lavoro elevabili (PLE) fornisce la preparazione teorica e pratica per l&#8217;uso sicuro delle piattaforme aeree e elevabili. Vengono trattate le modalit\u00e0 operative corrette, la gestione dei rischi specifici, le procedure di emergenza e le normative di sicurezza, con prove pratiche per l\u2019utilizzo delle attrezzature.<\/p>","protected":false},"featured_media":5646,"template":"","meta":{"_acf_changed":false,"wds_primary_product_brand":0,"wds_primary_product_cat":0},"product_brand":[],"product_cat":[49,66,37],"product_tag":[],"class_list":["post-5374","product","type-product","status-publish","has-post-thumbnail","product_cat-aula-e-videoconferenza","product_cat-formazione-attrezzature-dpi","product_cat-tutti-i-corsi","first","outofstock","virtual","taxable","product-type-simple"],"acf":{"durata":"8-10","modalita_di_erogazione":"In sede","sedi":"Sede SCILLA in Via Naro, 81 \u2013 Pomezia (RM) oppure su richiesta presso la sede del cliente","frequenza_obbligatoria":"90%","destinatari_del_corso":"Lavoratori e tecnici che operano con piattaforme elevabili nei cantieri, magazzini e strutture industrialiOperatori incaricati della conduzione di PLE in altezzaResponsabili della sicurezza per lavori in quota e utilizzo di attrezzature elevabili","certificazione":"Al termine del corso, superato il test di verifica dell\u2019apprendimento, verr\u00e0 rilasciato un attestato di formazione valido ai fini di legge, in conformit\u00e0 alla normativa vigente."},"meta_box":[],"_links":{"self":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product\/5374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media\/5646"}],"wp:attachment":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media?parent=5374"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_brand?post=5374"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_cat?post=5374"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_tag?post=5374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}