{"id":5379,"date":"2025-04-28T12:56:43","date_gmt":"2025-04-28T10:56:43","guid":{"rendered":"https:\/\/dev.scillasb.com\/?post_type=product&#038;p=5379"},"modified":"2025-05-27T12:21:53","modified_gmt":"2025-05-27T10:21:53","slug":"corso-di-formazione-prses-addetti-alla-verifica-delle-scaffalature","status":"publish","type":"product","link":"https:\/\/scillasb.com\/en\/product\/corso-di-formazione-prses-addetti-alla-verifica-delle-scaffalature\/","title":{"rendered":"Corso di formazione PRSES &#8211; Addetti alla verifica delle scaffalature"},"content":{"rendered":"<h4>PROGRAMMA DEL CORSO<\/h4>\n<p>in ottemperanza al D.lgs. 81\/2008 e s.m.i. &#8211; UNI EN 15635 &#8211; UNI EN 15878 in data 07 marzo 2024<\/p>\n<p><strong>FONDAMENTI GIURIDICI<\/strong><\/p>\n<ul>\n<li>Legislazione e normativa sicurezza applicabile<\/li>\n<li>La manutenzione programmata<\/li>\n<li>Figure di responsabilit\u00e0<\/li>\n<li>Responsabilit\u00e0 della validazione della scaffalatura<\/li>\n<li>Datore di lavoro e Dirigente: la responsabilit\u00e0 di vigilare UNI EN15635:2009<\/li>\n<li>Normative riguardanti le scaffalature industriali<\/li>\n<li>Classificazione delle scaffalature secondo la norma UNI EN 15878<\/li>\n<li>La figura del PRSES secondo la norma UNI EN 15635 GESTIONE DELLE NON CONFORMIT\u00c0<\/li>\n<li>Nomenclatura<\/li>\n<li>Cenni di calcolo strutturale e Targa di portata<\/li>\n<li>Deformazioni delle spalle e dei correnti<\/li>\n<li>Le spine di sicurezza<\/li>\n<li>Tolleranze di verticalit\u00e0<\/li>\n<li>Pavimentazioni e corsie<\/li>\n<li>Verifica sullo stato di conservazione<\/li>\n<li>Protezioni contro l\u2019impatto<\/li>\n<li>La classificazione del danno nelle scaffalature<\/li>\n<li>Unit\u00e0 di carico e Pulizia delle corsie CHECK LIST ISPEZIONE<\/li>\n<li>Controlli periodici consigliati<\/li>\n<li>Esercitazione finale del corso<\/li>\n<li>TEST FINALE.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Percorso formativo per Preposti alla Sicurezza delle Scaffalature Industriali (PRSES), in conformit\u00e0 alla norma UNI EN 15635. Fornisce le conoscenze per l\u2019ispezione e la gestione in sicurezza delle scaffalature.<\/p>","protected":false},"featured_media":5609,"template":"","meta":{"_acf_changed":false,"wds_primary_product_brand":0,"wds_primary_product_cat":0},"product_brand":[],"product_cat":[49,66,37],"product_tag":[],"class_list":["post-5379","product","type-product","status-publish","has-post-thumbnail","product_cat-aula-e-videoconferenza","product_cat-formazione-attrezzature-dpi","product_cat-tutti-i-corsi","first","outofstock","virtual","taxable","product-type-simple"],"acf":{"durata":"4","modalita_di_erogazione":"In Sede\/videoconferenza","sedi":"Sede SCILLA in Via Naro, 81 \u2013 Pomezia (RM) oppure su richiesta presso la sede del cliente","frequenza_obbligatoria":"90%","destinatari_del_corso":"Lavoratori addetti alla manutenzione e verifica delle scaffalature in magazzini e ambienti industrialiTecnici incaricati della gestione e manutenzione delle strutture di stoccaggioResponsabili della sicurezza nelle operazioni di movimentazione e stoccaggio","certificazione":"Al termine del corso, superato il test di verifica dell\u2019apprendimento, verr\u00e0 rilasciato un attestato di formazione valido ai fini di legge, in conformit\u00e0 alla normativa vigente."},"meta_box":[],"_links":{"self":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product\/5379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media\/5609"}],"wp:attachment":[{"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/media?parent=5379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_brand?post=5379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_cat?post=5379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/scillasb.com\/en\/wp-json\/wp\/v2\/product_tag?post=5379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}